{"id":81,"count":1,"description":"","link":"https:\/\/www.nicuc.ac.jp\/blog\/tag\/%e5%86%a0%e8%a9%9e\/","name":"\u51a0\u8a5e","slug":"%e5%86%a0%e8%a9%9e","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u51a0\u8a5e \u4e00\u89a7 - \u5927\u5b66\u7559\u5b66\u30d6\u30ed\u30b0<\/title>\n<meta name=\"description\" content=\"\u51a0\u8a5e \u306e\u30bf\u30b0\u306e\u4ed8\u3044\u305f\u8a18\u4e8b\u4e00\u89a7\u3002\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nicuc.ac.jp\/blog\/tag\/\u51a0\u8a5e\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u51a0\u8a5e \u4e00\u89a7 - \u5927\u5b66\u7559\u5b66\u30d6\u30ed\u30b0\" \/>\n<meta property=\"og:description\" content=\"\u51a0\u8a5e \u306e\u30bf\u30b0\u306e\u4ed8\u3044\u305f\u8a18\u4e8b\u4e00\u89a7\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nicuc.ac.jp\/blog\/tag\/\u51a0\u8a5e\/\" \/>\n<meta property=\"og:site_name\" content=\"\u5927\u5b66\u7559\u5b66\u30d6\u30ed\u30b0\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.nicuc.ac.jp\\\/blog\\\/tag\\\/%e5%86%a0%e8%a9%9e\\\/\",\"url\":\"https:\\\/\\\/www.nicuc.ac.jp\\\/blog\\\/tag\\\/%e5%86%a0%e8%a9%9e\\\/\",\"name\":\"\u51a0\u8a5e \u4e00\u89a7 - \u5927\u5b66\u7559\u5b66\u30d6\u30ed\u30b0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nicuc.ac.jp\\\/blog\\\/#website\"},\"description\":\"\u51a0\u8a5e \u306e\u30bf\u30b0\u306e\u4ed8\u3044\u305f\u8a18\u4e8b\u4e00\u89a7\u3002\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nicuc.ac.jp\\\/blog\\\/tag\\\/%e5%86%a0%e8%a9%9e\\\/#breadcrumb\"},\"inLanguage\":\"ja\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nicuc.ac.jp\\\/blog\\\/tag\\\/%e5%86%a0%e8%a9%9e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u30db\u30fc\u30e0\",\"item\":\"https:\\\/\\\/www.nicuc.ac.jp\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u51a0\u8a5e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nicuc.ac.jp\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.nicuc.ac.jp\\\/blog\\\/\",\"name\":\"\u5927\u5b66\u7559\u5b66\u30d6\u30ed\u30b0\",\"description\":\"\u201c\u5927\u5b66\u7559\u5b66\u201d\u3068\u3044\u3046\u5922\u3092\u5b9f\u73fe\u306b\u5909\u3048\u308b\u5fdc\u63f4\u60c5\u5831\u30da\u30fc\u30b8!\u3042\u306a\u305f\u306e\u5922\u304c\u3082\u3063\u3068\u52a0\u901f\u3059\u308b\u306e\u3092\u30a4\u30e1\u30fc\u30b8\u3001\u305d\u3057\u3066\u5b9f\u611f\u3057\u3088\u3046\u3002\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nicuc.ac.jp\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nicuc.ac.jp\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nicuc.ac.jp\\\/blog\\\/#organization\",\"name\":\"NIC International College in Japan\",\"url\":\"https:\\\/\\\/www.nicuc.ac.jp\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/www.nicuc.ac.jp\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nicuc.ac.jp\\\/blog\\\/wp\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/icon-512x512.png\",\"contentUrl\":\"https:\\\/\\\/www.nicuc.ac.jp\\\/blog\\\/wp\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/icon-512x512.png\",\"width\":512,\"height\":512,\"caption\":\"NIC International College in Japan\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nicuc.ac.jp\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u51a0\u8a5e \u4e00\u89a7 - \u5927\u5b66\u7559\u5b66\u30d6\u30ed\u30b0","description":"\u51a0\u8a5e \u306e\u30bf\u30b0\u306e\u4ed8\u3044\u305f\u8a18\u4e8b\u4e00\u89a7\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nicuc.ac.jp\/blog\/tag\/\u51a0\u8a5e\/","og_locale":"ja_JP","og_type":"article","og_title":"\u51a0\u8a5e \u4e00\u89a7 - \u5927\u5b66\u7559\u5b66\u30d6\u30ed\u30b0","og_description":"\u51a0\u8a5e \u306e\u30bf\u30b0\u306e\u4ed8\u3044\u305f\u8a18\u4e8b\u4e00\u89a7\u3002","og_url":"https:\/\/www.nicuc.ac.jp\/blog\/tag\/\u51a0\u8a5e\/","og_site_name":"\u5927\u5b66\u7559\u5b66\u30d6\u30ed\u30b0","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.nicuc.ac.jp\/blog\/tag\/%e5%86%a0%e8%a9%9e\/","url":"https:\/\/www.nicuc.ac.jp\/blog\/tag\/%e5%86%a0%e8%a9%9e\/","name":"\u51a0\u8a5e \u4e00\u89a7 - \u5927\u5b66\u7559\u5b66\u30d6\u30ed\u30b0","isPartOf":{"@id":"https:\/\/www.nicuc.ac.jp\/blog\/#website"},"description":"\u51a0\u8a5e \u306e\u30bf\u30b0\u306e\u4ed8\u3044\u305f\u8a18\u4e8b\u4e00\u89a7\u3002","breadcrumb":{"@id":"https:\/\/www.nicuc.ac.jp\/blog\/tag\/%e5%86%a0%e8%a9%9e\/#breadcrumb"},"inLanguage":"ja"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nicuc.ac.jp\/blog\/tag\/%e5%86%a0%e8%a9%9e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/www.nicuc.ac.jp\/blog\/"},{"@type":"ListItem","position":2,"name":"\u51a0\u8a5e"}]},{"@type":"WebSite","@id":"https:\/\/www.nicuc.ac.jp\/blog\/#website","url":"https:\/\/www.nicuc.ac.jp\/blog\/","name":"\u5927\u5b66\u7559\u5b66\u30d6\u30ed\u30b0","description":"\u201c\u5927\u5b66\u7559\u5b66\u201d\u3068\u3044\u3046\u5922\u3092\u5b9f\u73fe\u306b\u5909\u3048\u308b\u5fdc\u63f4\u60c5\u5831\u30da\u30fc\u30b8!\u3042\u306a\u305f\u306e\u5922\u304c\u3082\u3063\u3068\u52a0\u901f\u3059\u308b\u306e\u3092\u30a4\u30e1\u30fc\u30b8\u3001\u305d\u3057\u3066\u5b9f\u611f\u3057\u3088\u3046\u3002","publisher":{"@id":"https:\/\/www.nicuc.ac.jp\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nicuc.ac.jp\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/www.nicuc.ac.jp\/blog\/#organization","name":"NIC International College in Japan","url":"https:\/\/www.nicuc.ac.jp\/blog\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.nicuc.ac.jp\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.nicuc.ac.jp\/blog\/wp\/wp-content\/uploads\/2019\/09\/icon-512x512.png","contentUrl":"https:\/\/www.nicuc.ac.jp\/blog\/wp\/wp-content\/uploads\/2019\/09\/icon-512x512.png","width":512,"height":512,"caption":"NIC International College in Japan"},"image":{"@id":"https:\/\/www.nicuc.ac.jp\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.nicuc.ac.jp\/blog\/wp-json\/wp\/v2\/tags\/81","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nicuc.ac.jp\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.nicuc.ac.jp\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.nicuc.ac.jp\/blog\/wp-json\/wp\/v2\/posts?tags=81"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}